{"id":4652,"date":"2026-05-13T14:58:34","date_gmt":"2026-05-13T14:58:34","guid":{"rendered":"https:\/\/stardance.co.nz\/?post_type=ttsd_class&#038;p=4652"},"modified":"2026-05-13T14:58:34","modified_gmt":"2026-05-13T14:58:34","slug":"test","status":"publish","type":"ttsd_class","link":"https:\/\/stardance.co.nz\/cn\/tt-classes\/test\/","title":{"rendered":"test"},"content":{"rendered":"<p>THis is a test<\/p>","protected":false},"featured_media":4638,"menu_order":0,"template":"","ttsd_class_category":[286],"ttsd_class_type":[],"class_list":["post-4652","ttsd_class","type-ttsd_class","status-publish","has-post-thumbnail","hentry","ttsd_class_category-test"],"_links":{"self":[{"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/ttsd_class\/4652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/ttsd_class"}],"about":[{"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/types\/ttsd_class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/media\/4638"}],"wp:attachment":[{"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/media?parent=4652"}],"wp:term":[{"taxonomy":"ttsd_class_category","embeddable":true,"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/ttsd_class_category?post=4652"},{"taxonomy":"ttsd_class_type","embeddable":true,"href":"https:\/\/stardance.co.nz\/cn\/wp-json\/wp\/v2\/ttsd_class_type?post=4652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}